{"id":23693,"date":"2024-06-28T07:25:05","date_gmt":"2024-06-28T10:25:05","guid":{"rendered":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/?p=23693"},"modified":"2024-07-12T12:26:24","modified_gmt":"2024-07-12T15:26:24","slug":"vila-portugal-zona-norte-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/","title":{"rendered":"Gradil de Ferro Vila Portugal &#8211; Zona Norte de S\u00e3o Paulo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Gradil  na Vila Portugal, Zona Norte de S\u00e3o Paulo?<\/h2>\n\n\n\n<p>Precisando de Gradil ? Se sim, voc\u00ea est\u00e1 no lugar certo! Estamos felizes em dizer que a <a href=\"https:\/\/solobrasileiro.com\/serralheria\/vila-portugal-zona-norte-de-sao-paulo\/\" rel=\"dofollow\" title=\"serralheria vila portugal zona norte de sao paulo\">serralheria<\/a> Solo Brasileiro atende   Vila Portugal, Zona Norte de S\u00e3o Paulo! Trabalhamos com a fabrica\u00e7\u00e3o de <strong>gradil de ferro para fechamento de \u00e1reas<\/strong>, nossa equipe est\u00e1 pronta para fornecer servi\u00e7os de alta qualidade. Desde a concep\u00e7\u00e3o at\u00e9 a instala\u00e7\u00e3o, garantimos um atendimento completo e personalizado para atender \u00e0s suas necessidades.<\/p>\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"998\" height=\"649\" src=\"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2024\/06\/Gradil-de-ferro-fechamento-de-areas-e-muros-serralheria-Solo-Brasileiro.jpg\" alt=\"gradil de ferro naVila Portugal- Zona Norte de S\u00e3o Paulo\" class=\"wp-image-1358\" srcset=\"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2024\/06\/Gradil-de-ferro-fechamento-de-areas-e-muros-serralheria-Solo-Brasileiro.jpg 998w, https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2024\/06\/Gradil-de-ferro-fechamento-de-areas-e-muros-serralheria-Solo-Brasileiro-768x499.jpg 768w\" sizes=\"auto, (max-width: 998px) 100vw, 998px\" \/><\/figure>\n\n\n\n<p>O <strong>gradil de ferro<\/strong> \u00e9 uma estrutura met\u00e1lica amplamente utilizada para fechamento de \u00e1reas e muros. Ele oferece seguran\u00e7a, durabilidade e um apelo est\u00e9tico que pode transformar a apar\u00eancia de qualquer espa\u00e7o. Na nossa <a href=\"https:\/\/solobrasileiro.com\/serralheria\/vila-portugal-zona-norte-de-sao-paulo\/\" rel=\"dofollow\" title=\"serralheria vila portugal zona norte de sao paulo\">serralheria<\/a>, nos especializamos na fabrica\u00e7\u00e3o de gradil de ferro de alta qualidade, atendendo \u00e0s necessidades espec\u00edficas de cada cliente.<\/p>\n\n\n\n<p>Quando se trata de seguran\u00e7a e durabilidade, o <strong>gradil de ferro<\/strong> \u00e9 uma escolha imbat\u00edvel. Este material \u00e9 resistente \u00e0s intemp\u00e9ries, o que significa que ele pode suportar sol, chuva e vento sem comprometer sua integridade estrutural. Al\u00e9m disso, o gradil de ferro \u00e9 uma solu\u00e7\u00e3o vers\u00e1til que pode ser personalizada de acordo com o design e as dimens\u00f5es necess\u00e1rias para o seu projeto.<\/p>\n\n\n\n<p>E se voc\u00ea estiver interessado em adicionar um <strong>gradil de ferro<\/strong> ao seu espa\u00e7o, <a>Solicite um or\u00e7amento conosco<\/a>! Nossa equipe est\u00e1 dispon\u00edvel para responder a todas as suas perguntas e ajudar voc\u00ea a encontrar a melhor solu\u00e7\u00e3o para o seu projeto. N\u00e3o importa a complexidade do seu pedido, estamos aqui para garantir que voc\u00ea receba um produto final que atenda \u00e0s suas expectativas.<\/p>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-d2da2050 wp-block-columns-is-layout-flex\" style=\"margin-bottom:0\">\n<div class=\"wp-block-column has-base-2-color has-text-color has-background has-link-color wp-elements-59fdc3ed8a0a0442818224013153eba7 is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:11px;background-color:#e8fcff;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h2 class=\"wp-block-heading has-contrast-color has-text-color has-link-color wp-elements-9dea5de9fa65d6c99422824fa45d5bed\" id=\"patron\" style=\"font-size:clamp(24.034px, 1.502rem + ((1vw - 3.2px) * 1.565), 40px);\"><strong>Por que devo escolher a <a href=\"https:\/\/solobrasileiro.com\/serralheria\/vila-portugal-zona-norte-de-sao-paulo\/\" rel=\"dofollow\" title=\"serralheria vila portugal zona norte de sao paulo\">serralheria<\/a> Solo Brasileiro?<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide is-style-wide--1\" \/>\n\n\n\n<p class=\"has-contrast-color has-text-color has-link-color wp-elements-fc3800f014e6e00874b6be5b4e44db14\">A <a href=\"https:\/\/solobrasileiro.com\/serralheria\/vila-portugal-zona-norte-de-sao-paulo\/\" rel=\"dofollow\" title=\"serralheria vila portugal zona norte de sao paulo\">serralheria<\/a> Solo Brasileiro tem mais de 12 Anos de atua\u00e7\u00e3o no mercado, com uma equipe altamente qualificada. Para garantir a durabilidade dos nossos produtos e servi\u00e7os, n\u00f3s utilizamos materiais de qualidade .<br>Trabalhamos conforme as suas necessidades e prefer\u00eancias, pois, praticamente todo projeto \u00e9 \u00fanico! Valorizamos a credibilidade de nossos clientes, entregando sempre o que prometemos com transpar\u00eancia e confian\u00e7a!<\/p>\n\n\n\n<p class=\"has-contrast-color has-text-color has-link-color wp-elements-c10159644a5b2f54b5307e3b8e916b0c\">Clica em Saiba Mais e confira fotos e v\u00eddeos dos nossos servi\u00e7os realizados e veja a qualidade que oferecemos:<\/p>\n\n\n\n<div class=\"wp-block-buttons alignfull is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-03627597 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 has-custom-font-size has-medium-font-size\"><a class=\"wp-block-button__link has-base-2-color has-contrast-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/solobrasileiro.com\/serralheria\/servicos-realizados\/\" style=\"border-style:none;border-width:0px;border-radius:20px;padding-top:var(--wp--preset--spacing--10);padding-bottom:var(--wp--preset--spacing--10)\">SAIBA MAIS<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto Custa Gradil de Ferro?<\/h2>\n\n\n\n<p>A pergunta que muitos fazem \u00e9:&nbsp;<strong>quanto custa gradil de ferro?<\/strong>&nbsp;O valor pode variar bastante dependendo de diversos fatores, como a espessura do ferro, o tipo de acabamento e a complexidade do design. Para obter um valor exato, \u00e9 essencial solicitar um or\u00e7amento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como Solicitar um Or\u00e7amento?<\/h2>\n\n\n\n<p>Para solicitar um or\u00e7amento de Gradil, voc\u00ea pode clicar nos bot\u00f5es abaixo e <a>entrar em contato conosco<\/a>! <\/p>\n\n\n\n<p>Atendemos  Vila Portugal, Zona Norte de S\u00e3o Paulo e outros bairros da regi\u00e3o, garantindo rapidez e efici\u00eancia no servi\u00e7o prestado. Entre em contato com nossa <a href=\"https:\/\/solobrasileiro.com\/serralheria\/vila-portugal-zona-norte-de-sao-paulo\/\" rel=\"dofollow\" title=\"serralheria vila portugal zona norte de sao paulo\">serralheria<\/a> e descubra como podemos ajudar a aumentar a seguran\u00e7a e beleza do seu im\u00f3vel.<\/p>\n\n\n\n\n\n\n<p><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o de Gradil de ferro para muros e fechamento de \u00e1reas &#8211; Vila Portugal , Zona Norte de S\u00e3o Paulo , suas vantagens para seguran\u00e7a e delimita\u00e7\u00e3o de espa\u00e7os Solicite Or\u00e7amento !<\/p>\n","protected":false},"author":1,"featured_media":1359,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103],"tags":[],"class_list":["post-23693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zona-norte-de-sao-paulo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gradil - Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o - Vila Portugal , Zona Norte de S\u00e3o Paulo | SOLO BRASILEIRO \u2600\ufe0f<\/title>\n<meta name=\"description\" content=\"Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o de Gradil de ferro para muros e fechamento de \u00e1reas - Vila Portugal , Zona Norte de S\u00e3o Paulo , suas vantagens para seguran\u00e7a e delimita\u00e7\u00e3o de espa\u00e7os Solicite Or\u00e7amento !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gradil - Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o - Vila Portugal , Zona Norte de S\u00e3o Paulo | SOLO BRASILEIRO \u2600\ufe0f\" \/>\n<meta property=\"og:description\" content=\"Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o de Gradil de ferro para muros e fechamento de \u00e1reas - Vila Portugal , Zona Norte de S\u00e3o Paulo , suas vantagens para seguran\u00e7a e delimita\u00e7\u00e3o de espa\u00e7os Solicite Or\u00e7amento !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"GRADIL - GRADES PARA MUROS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/youtube.com\/solobrasileiro\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T10:25:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T15:26:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2021\/08\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SERRALHERIA SOLO BRASILEIRO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SERRALHERIA SOLO BRASILEIRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/\",\"url\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/\",\"name\":\"Gradil - Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o - Vila Portugal , Zona Norte de S\u00e3o Paulo | SOLO BRASILEIRO \u2600\ufe0f\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2021\\\/08\\\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg\",\"datePublished\":\"2024-06-28T10:25:05+00:00\",\"dateModified\":\"2024-07-12T15:26:24+00:00\",\"description\":\"Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o de Gradil de ferro para muros e fechamento de \u00e1reas - Vila Portugal , Zona Norte de S\u00e3o Paulo , suas vantagens para seguran\u00e7a e delimita\u00e7\u00e3o de espa\u00e7os Solicite Or\u00e7amento !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2021\\\/08\\\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg\",\"contentUrl\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2021\\\/08\\\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg\",\"width\":1200,\"height\":671,\"caption\":\"gradil de ferro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/vila-portugal-zona-norte-de-sao-paulo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gradil de Ferro Vila Portugal &#8211; Zona Norte de S\u00e3o Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/#website\",\"url\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/\",\"name\":\"GRADIL - GRADES PARA MUROS\",\"description\":\"Escadas de Ferro \\\/ Escadas Met\u00e1licas &amp; Serralheria Geral &gt;&gt;\",\"publisher\":{\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/#organization\"},\"alternateName\":\"Serralheria Solo Brasileiro\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/#organization\",\"name\":\"Serralheria Solo Brasileiro\",\"alternateName\":\"Serralheria Solo Brasileiro\",\"url\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Serralheria Solo Brasileiro\"},\"image\":{\"@id\":\"https:\\\/\\\/solobrasileiro.com\\\/serralheria\\\/gradil\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/youtube.com\\\/solobrasileiro\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gradil - Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o - Vila Portugal , Zona Norte de S\u00e3o Paulo | SOLO BRASILEIRO \u2600\ufe0f","description":"Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o de Gradil de ferro para muros e fechamento de \u00e1reas - Vila Portugal , Zona Norte de S\u00e3o Paulo , suas vantagens para seguran\u00e7a e delimita\u00e7\u00e3o de espa\u00e7os Solicite Or\u00e7amento !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/","og_locale":"pt_BR","og_type":"article","og_title":"Gradil - Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o - Vila Portugal , Zona Norte de S\u00e3o Paulo | SOLO BRASILEIRO \u2600\ufe0f","og_description":"Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o de Gradil de ferro para muros e fechamento de \u00e1reas - Vila Portugal , Zona Norte de S\u00e3o Paulo , suas vantagens para seguran\u00e7a e delimita\u00e7\u00e3o de espa\u00e7os Solicite Or\u00e7amento !","og_url":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/","og_site_name":"GRADIL - GRADES PARA MUROS","article_publisher":"https:\/\/youtube.com\/solobrasileiro","article_published_time":"2024-06-28T10:25:05+00:00","article_modified_time":"2024-07-12T15:26:24+00:00","og_image":[{"width":1200,"height":671,"url":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2021\/08\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg","type":"image\/jpeg"}],"author":"SERRALHERIA SOLO BRASILEIRO","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"SERRALHERIA SOLO BRASILEIRO","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/","url":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/","name":"Gradil - Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o - Vila Portugal , Zona Norte de S\u00e3o Paulo | SOLO BRASILEIRO \u2600\ufe0f","isPartOf":{"@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/#primaryimage"},"image":{"@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2021\/08\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg","datePublished":"2024-06-28T10:25:05+00:00","dateModified":"2024-07-12T15:26:24+00:00","description":"Fabrica\u00e7\u00e3o e Instala\u00e7\u00e3o de Gradil de ferro para muros e fechamento de \u00e1reas - Vila Portugal , Zona Norte de S\u00e3o Paulo , suas vantagens para seguran\u00e7a e delimita\u00e7\u00e3o de espa\u00e7os Solicite Or\u00e7amento !","breadcrumb":{"@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/#primaryimage","url":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2021\/08\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg","contentUrl":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-content\/uploads\/sites\/20\/2021\/08\/gradil-de-ferro-serralheria-Solo-Brasileiro.jpg","width":1200,"height":671,"caption":"gradil de ferro"},{"@type":"BreadcrumbList","@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/vila-portugal-zona-norte-de-sao-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/"},{"@type":"ListItem","position":2,"name":"Gradil de Ferro Vila Portugal &#8211; Zona Norte de S\u00e3o Paulo"}]},{"@type":"WebSite","@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/#website","url":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/","name":"GRADIL - GRADES PARA MUROS","description":"Escadas de Ferro \/ Escadas Met\u00e1licas &amp; Serralheria Geral &gt;&gt;","publisher":{"@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/#organization"},"alternateName":"Serralheria Solo Brasileiro","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/#organization","name":"Serralheria Solo Brasileiro","alternateName":"Serralheria Solo Brasileiro","url":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Serralheria Solo Brasileiro"},"image":{"@id":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/youtube.com\/solobrasileiro"]}]}},"_links":{"self":[{"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/posts\/23693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/comments?post=23693"}],"version-history":[{"count":0,"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/posts\/23693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/media\/1359"}],"wp:attachment":[{"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/media?parent=23693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/categories?post=23693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solobrasileiro.com\/serralheria\/gradil\/wp-json\/wp\/v2\/tags?post=23693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}